{"id":170,"date":"2022-05-18T15:58:37","date_gmt":"2022-05-18T19:58:37","guid":{"rendered":"https:\/\/stilettosupply.com\/?page_id=170"},"modified":"2024-03-11T12:24:21","modified_gmt":"2024-03-11T16:24:21","slug":"certification-search","status":"publish","type":"page","link":"https:\/\/stilettosupply.com\/es\/resources\/certification-search\/","title":{"rendered":"B\u00fasqueda de Certificaci\u00f3n de Esterilizaci\u00f3n"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1653355939921 vc_row-has-fill wd-rs-628c358e12ac6\"><div class=\"wpb_column library-doc vc_column_container vc_col-sm-12 vc_col-md-offset-1 vc_col-md-10 vc_col-has-fill wd-z-index wd-alignment-left wd-rs-628c36d43777c\"><div class=\"vc_column-inner vc_custom_1653356264117\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element h-cat-box\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t<input type=\"hidden\" name=\"category-search-1\" value=\"\" class=\"category-search-1\">\n\t\t<table id=\"document-library-1\" class=\"document-library-table\" data-page-length=\"18446744073709551615\" data-paging=\"true\" data-click-filter=\"true\" data-scroll-offset=\"15\" data-order=\"[]\" cellspacing=\"0\" width=\"100%\">\n\t\t\t<thead><tr><th data-name=\"title\" data-priority=\"1\" data-width=\"\" data-orderable=\"true\">T\u00edtulo<\/th><th data-name=\"link\" data-priority=\"4\" data-width=\"\" data-orderable=\"false\">Enlace<\/th><\/tr><\/thead>\t\t\t<tbody>\n\t\t\t\t<tr><td>Certificate of E.O. Gas Sterilization Lot #:   100S (Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/05\/LOT-100S-4.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"LOT-100S-4.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:   240716 240916 (Rec. Tubes)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/03\/20250220001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250220001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:   240916 241016 241106 241116 241206 241216 241228  250108 250116 250216 250306 250326 250406 (Needles, Tapers, Tweezers, Sticks, Bead Changer, Piercing Packs, Sample Kits, Markers, Rec. Tubes, Steel Rec. Tubes)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/05\/20250311001-2-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250311001-2-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:   240916 241016 241116 241206 241228 250108 250216 250306 (Needles, Tapers, Sticks, Clamps, Rec. Tubes &#038; Markers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/03\/20250205006-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250205006-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:   241016 241206 241226 241228 250108 250216 250306 (Needles &#038; Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/03\/20250310005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250310005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:   241128  (Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/05\/20241119001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20241119001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:   250326 (Markers, Steel Rec. Tubes)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/04\/20250311001-1-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250311001-1-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 220715 221030 240616 240708 240716 240816 240908 240916 241012 (Agujas, conos, abrazaderas, varillas, marcadores, tubos de recepci\u00f3n, paquetes de perforaci\u00f3n y kits de muestra)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/11\/20240902001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240902001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 220715, 220815, 220920 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220914003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220914003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 220715, 230605, 240116, 240308, 240416, 240516, 240605, 240616, 240708, 240716, 240812, 240816 (Agujas, Conos, Tubos Rec. de Acero, Tubos Rec., Marcadores, Abrazaderas de Septo, Cambiadores de Cuentas))<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/09\/20240707001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240707001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  221030 240616 240916 241016 241116 241128 241206 241216 241226 241228 (Piercing Needles, Tapers, Piercing Packs, Rec. Tubes)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/01\/20241217001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20241217001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 221030, 230605, 231016, 231216, 240116, 240308, 240516, 240616, 240708, 240716 (Agujas, conos, marcadores de piel, tubos receptores, paquetes de perforaci\u00f3n, varillas de perforaci\u00f3n, abrazaderas, pinzas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/08\/20240606004-Certificate-of-E.O.Gas-sterilization21.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240606004-Certificate-of-E.O.Gas-sterilization21.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 221115, 230510, 230605, 231016, 231116, 231210, 231216, 240116 (marcadores de piel, paquetes de perforaci\u00f3n, agujas y conos para perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/02\/20231229002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231229002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  221215 240816 240916 241012 241016 241028 241106 241108 (Needles, Tapers, Clamps, Sticks, Markers, Piercing Packs, Packs with Drapes)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/12\/20241010001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20241010001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 230605, 231016, 231210, 240116 (agujas y puntas de perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/02\/20231229003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231229003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 231016, 240116, 240220, 240308, 240506, 240516, 240610, 240616, 240708 (agujas y conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/07\/20240606002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240606002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  240308 240906 241106 241116 241206 241228 250108 250216 250416 (Needles, Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/05\/20250417001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250417001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240308, 240516 (Marcadores de piel)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/07\/20240420004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240420004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240308, 240616, 240812, 240816, 240916 (Agujas, conos, pinzas para tabique, tubos de recepci\u00f3n, abrazaderas, cambiadores de cuentas, anillos de colocaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/09\/20240707002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240707002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240328, 240516, 240616 (Marcadores de piel)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/07\/20240420005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240420005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240426 (Joyas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/08\/EO-Gas-Certificate-240426.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"EO-Gas-Certificate-240426.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240516, 240616 (Tapers &amp; Drapes)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/07\/20240606001-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240606001-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240516, 240716 (Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/08\/20240606003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240606003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  240606 240916 241016 241106 241108 241116 (Piercing Needles, Tapers, Piercing Packs, Markers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/12\/202411006001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"202411006001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240708 (Agujas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/08\/20240606005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240606005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240716 (Joyas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/09\/20240827001-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240827001-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240716 (Joyas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/09\/20240827001-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240827001-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  240716 240916 250108 250306 250326 250406 250408 (Needles, Tapers, Clamps)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/05\/20250417002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250417002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  240716 241016 (Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/12\/20241209002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20241209002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  240716 2411062 (Piercing Jewelry &#038; Posts)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/11\/20241113001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20241113001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240816 (cambiadores de perlas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/09\/20240903001-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240903001-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240816, 240906, 240908, 240916 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/10\/20241009001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20241009001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  240916 241226 250108 250216 250406 250408 250416 (Needles, Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/05\/20250430001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250430001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  241203 (Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/12\/LOT-0890.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"LOT-0890.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #:  250106 250511 (Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/05\/20250510001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250510001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 101S  (Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/07\/LOT-101S.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"LOT-101S.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 102S (Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/08\/LOT-102S.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"LOT-102S.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 103S (Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/10\/LOT-103S.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"LOT-103S.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 106S (Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/03\/LOT-106S.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"LOT-106S.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 190825, 190901, 190911, 191010 (Marcador, Abrazadera)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20191005001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20191005001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 191220, 200115 (Joyer\u00eda para piercing, agujas, cirios)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/02\/20200113001-Certificate-of-E.O.-Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20200113001-Certificate-of-E.O.-Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 191220, 200120, 200315, 200320, 200520, 200615 (Aguja, Cono, Abrazadera, Joyer\u00eda, Cubierta de Silicona)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20200624001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20200624001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 191220, 200120, 200315, 200520, 200531, 200310 (Agujas, Conos, Abrazaderas, Varillas, Tubos Rec., Cubiertas de Herramientas de Silicona)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20200608001-Certificate-of-E.S.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20200608001-Certificate-of-E.S.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 200120, 200315, 200520, 200531, 200610 (Agujas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20200819001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20200819001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 200120, 200930, 210515, 210630, 210820, 210830, 210910, 210920, 210930, 211010 (Agujas, Conos, Abrazaderas, Varillas, Tubos Rec., Marcadores, Cubiertas de Herramientas de Silicona)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721009-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721009-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 200315, 200630, 210301, 210420, 210530, 210620 (abrazadera, varilla, tubo rec., marcador)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210604005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210604005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 200520, 200830 (C\u00f3nico)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20201010001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20201010001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 200520, 200830, 200920 (Aguja)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20200904002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20200904002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 200630, 201230, 210130, 210320 (Marcador)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210327001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210327001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 200630, 210515, 210610 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210604001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210604001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 200920, 210301, 210515, 210630, 210720 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 201030, 200901 (Aguja, Cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20201106001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20201106001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 201030, 201130 (Aguja, Cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20201207002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20201207002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 201030, 201230, 210301 (Aguja, Cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210326001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210326001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 201030, 210301 (Aguja, Cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210315001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210315001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 201130, 201230 (Aguja, Cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210108001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210108001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 201230, 200630, 201230 (Aguja, Marcador, Pinza)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210203001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210203001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 201230, 210301 (Aguja, Cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210224004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210224004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 210301 (Aguja, Cono) 5 de abril<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210224002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210224002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 210301 (Aguja, Cono) 7 de abril<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210224003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210224003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210301 (Aguja, Cono) Marzo<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210224001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210224001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 210301, 210515, 210630 (aguja, cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210604004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210604004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210420 (Marcador)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210425002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210425002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210420 (Marcador)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210425001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210425001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210420 (Aguja, Cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210224005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210224005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 210420, 210515 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210224006-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210224006-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210420, 210515 (C\u00f3nicos, Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210408001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210408001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210420, 210630, 210730, 210820 (Abrazaderas, Varillas, Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 210515, 210630 (aguja, cono)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210604003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210604003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 210515, 210630, 210820, 210830, 210910 (aguja, cono, marcador)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210721003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210620 (Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210604002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210604002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210630 (Abrazadera, Palo, Tubo Rec., Marcador)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2022\/05\/20210604006-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210604006-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210630, 210720, 210820 (Agujas, Conos, Tubos Rec. de Acero, Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 210630, 210820 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721006-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721006-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 210630, 210820 (Agujas\/Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/202107210016-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"202107210016-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210820 (Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210820, 210910, 211010 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721008-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721008-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210820, 210910, 211010, 211130, 211210, 211230 (Agujas, Conos, Tubos Rec.)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721012-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721012-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210910 (Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721007-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721007-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210910, 211010, 211130 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721011-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721011-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210910, 211110, 220110, 220215 (Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721018-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721018-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 210910, 211130, 220415, 220615, 220620, 220715, 220730, 220815, 220830 (Agujas, Conos, Paquetes de Perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220914001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220914001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 211010, 211130, 211230, 220110, 220215, 220415, 220515, 220615, 220620 (agujas\/conos\/abrazaderas\/tubos receptores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220517003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220517003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 211010, 211130, 220215, 220715, 220815, 220930, 221115, 221130, 221215, 230510, 230605 (agujas, conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230609001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230609001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 211010, 211230 (Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721013-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721013-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 211010, 211230, 220110, 220215 (Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721014-Certificate-of-E.O.Gas-sterilization1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721014-Certificate-of-E.O.Gas-sterilization1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 211010, 220110, 220630, 220715, 220815, 220830, 220920, 220930 (Agujas\/Conos\/Abrazaderas\/Paquetes de perforaci\u00f3n\/Cubiertas de silicona)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220914004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220914004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas OE Lote #: 211010, 220730, 220815, 220830, 220930, 221030, 221115, 221130, 221215 (Agujas, Conos, Abrazaderas, Varillas, Marcadores, Tubos Rec.)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220914009-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220914009-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 211015, 211030, 211130, 220830, 220920, 220930, 221015, 221020, 221030, 221115, 221120, 221130, 221215, 2212 20, 221230 (agujas, conos, abrazaderas, varillas, paquetes de perforaci\u00f3n, marcadores , Tubos Rec.)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220914002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220914002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 211030, 211115 (barras, tubos rec.)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721010-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721010-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas OE Lote #: 211130, 211230, 220515, 220815, 220920, 221115, 221130, 221215, 230215 (Agujas, Conos, Varillas, Marcadores, Tubos Rec.)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230201004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230201004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 211130, 220215 (Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721015-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721015-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 211230, 220110, 220215, 220415 (Agujas\/Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721019-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721019-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 211230, 220415, 220515 (Agujas, Marcadores, Paquetes de Perforaci\u00f3n, Tubos Rec.)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721020-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721020-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 220110, 220215 (Agujas\/Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20210721017-Certificate-of-E.O.Gas-sterilization1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20210721017-Certificate-of-E.O.Gas-sterilization1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 220415, 220515, 220615, 220620 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220517002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220517002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 220415, 220730, 220830, 220910 (Agujas, Conos, Abrazaderas, Paquetes de Perforaci\u00f3n, Tubos Rec. de Acero)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220517009-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220517009-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 220615, 220630 (Conos, Abrazaderas, Marcadores, Paquetes de Perforaciones)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220517004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220517004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 220630, 220830 (Conos, Paquetes de perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220517007-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220517007-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 220730, 220830 (Conos, Paquetes de perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220517008-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220517008-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas OE Lote #: 220815, 220930, 221030, 221115, 221130 (Agujas, Conos, Abrazaderas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220914008-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220914008-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 220830 (Paquetes de Perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220517010-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220517010-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 220930, 220830 (Agujas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220914005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220914005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 221030, 230215, 230605, 230728, 230804, 230817, 230822 (Agujas, Conos, Tubos Rec. de Acero, Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230609003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230609003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas OE Lote #: 221115 (Conos, Tubos Rec., Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20220914006-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20220914006-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 221115, 221130, 230215, 230510, 230605, 230804, 230822, 230828, 230914, 230917, 231016, 231116 (abrazaderas, paquetes de perforaci\u00f3n, agujas, Conos, varillas, cubiertas de silicona, tubos receptores))<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2023\/11\/20231013004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231013004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 221115, 221215, 230524, 230605, 230820, 230828, 230917, 231016, 231116, 231210, 231216, 240116, 240220, 06, 240116, 240306, 240308 (Agujas para piercing, Conos, Abrazaderas, Piercing palos, tubos receptores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/04\/20240223004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240223004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 221115, 230215 (Agujas, Conos, Tubos Rec.)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230201002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230201002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 221130, 231016, 231116 (Paquetes\/marcadores de perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2023\/12\/20231013006-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231013006-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 221215 (Agujas, Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230201001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230201001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas OE Lote #: 221215, 230215, 230415, 230420 (Agujas, Conos, Tubos Rec., Marcadores, Pinzas para Septum)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230201005-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230201005-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 221215, 230215, 230605, 230828, 230912 (Agujas\/Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20231013002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231013002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 221215, 230510, 230524, 230605, 230917, 231016, 231116 (Aguja, Cono, Marcador)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2023\/11\/20231013003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231013003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 230215 (Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230201003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230201003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 230215, 230513 (Cios, Joyer\u00eda)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230518001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230518001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 230215,230510, 231116 (Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2023\/12\/20231013008-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231013008-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 230415 (Abrazaderas de tabique)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230308002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230308002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 230415, 230510, 230516 (abrazaderas de tabique, tubos rec. de acero, marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230308001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230308001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 230510, 230605 (Agujas, Conos, Tubos Rec., Marcadores))<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230728002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230728002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 230510, 230605, 240416, 240516 (agujas y puntas de perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/06\/20240420003-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240420003-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 230524, 230605 (Agujas, Cilindros)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230728001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230728001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 230605, 240116, 240308, 240325, 240328, 240416, 240508, 240516 (agujas y conos para perforaci\u00f3n, abrazaderas, varillas para perforaci\u00f3n, tubos receptores, tubos rec. de acero)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/06\/20240420001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240420001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 230718 (Joyas)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230804001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230804001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 230718, 231015, 231016 (Joyas para piercing)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2023\/12\/20231115001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231115001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 230804, 230917 (Marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20230609004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20230609004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 230804, 231016, 231116 (barra perforadora, marcadores para la piel)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2023\/11\/20231013005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231013005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 230804, 231016, 231116 (barras perforadoras\/marcadores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2023\/12\/20231013005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231013005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 230822, 231016, 231116, 240116 (abrazaderas, varillas perforadoras, tubos receptores, marcadores de piel, paquetes de muestra y paquetes de perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/01\/20231229001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231229001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas OE Lote #: 230914, 231116 (Agujas\/Conos)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2023\/12\/20231013007-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20231013007-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 231116, 231216 (Joyas para piercing)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/02\/20240131002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240131002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 231210, 240116, 240308, 240325, 240328, 240416 (Paquetes de perforaci\u00f3n, tubos receptores, marcadores de piel)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/05\/20240223005-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240223005-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 240116 (Joyas para piercing)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/02\/20240131001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240131001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 240116 (Joyas para piercing)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/02\/20240201001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240201001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 240116 (Paquetes de Perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/03\/20240223003-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240223003-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240308 (Paquetes de perforaci\u00f3n, tubos receptores)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/04\/20240223001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240223001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 240308 (Paquetes de Perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/03\/20240223002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240223002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 240416 (Paquetes de Perforaci\u00f3n)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/06\/20240420002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240420002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 240516 (Joyas para piercing)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/06\/20240520001-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240520001-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de Esterilizaci\u00f3n con Gas EO Lote #: 240516 (Joyas para piercing)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2024\/06\/20240521001-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20240521001-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificado de esterilizaci\u00f3n con gas EO Lote #: 240605, 240516 (Abrazaderas perforadoras y abrazaderas de pinza)<\/td><td><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 240916, 241116, 241206, 250216, 250306, 250326, 250406, 250606, 250616, 250706, 250708, 250726, 250728, 250808, 250816  (Needles\/Tapers, Plastic Tools)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/09\/20250822001-Eo-Gas-Certification-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250822001-Eo-Gas-Certification-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 241010   (Needles)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/09\/20250207001-Eo-Gas-Certification-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250207001-Eo-Gas-Certification-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 241016 241116 250306 250326 250406 250416 250508 250516 250518 250606 250608 250616 250618 250706 250708   (Needles, Tapers, Hemo Clamps, Clamps, Sticks, Earth Series Tools, Tweezer, Steel Rec. Tubes, Markers, Piercing Packs, Bead Changers))<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/08\/20250609002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250609002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 241116 241226 250108 250216 250306 250326 250406 250408 250416 250508 250516 250518  (Piercing Tools, Needles, Tapers, Tweezers, Clamps, Markers, Rec. Tubes, Bead Changers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/07\/20250407002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250407002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 241116 241226 250108 250326 250406 250408 250416 250516 250518 250606  (Piercing Tools, Needles, Tapers, Steel Tubes, Clamps, Markers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/06\/20250407001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250407001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 241116, 241206, 241228, 250306, 250326, 250406, 250408, 250416, 250508, 250516, 250606, 250616, 250618, 250702, 250706, 250716, 250718, 250726, 250728, 250806, 250816, 250906 (Needles\/Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/09\/20250904001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250904001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 241120 250920 251002 (Bead Changers, Needles)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/10\/20250903002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250903002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 241120, 241228, 250616, 250708, 250816, 250819, 250906, 250920, 251002, 251016, 251118, 251130 (Needles &#038; Plastic Tools)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/12\/20251127001-Eo-Gas-Certification.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20251127001-Eo-Gas-Certification.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250106  (Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/06\/20250609001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250609001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250306 ,250406, 250408, 250416, 250516, 250616, 250716, 250708, 250718, 250728, 250806, 250808, 250816, 250818, 250819, 250906, 250908, 250916, 250920, 250925, 251008 (Needles &#038; Plastic Tools)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/12\/20250917001-Eo-Gas-Certification.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250917001-Eo-Gas-Certification.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250306 250406 250408 250514 250516 250526 250606 250608 250616 250618 250702 250706 250708 250716 250718 250726 250728 250806 250808 250816 250906 (Needles, Tapers, Sticks, Clamps, Tweezers, Rec. Tubes, Bead Changers, Earth Series Piercing Tools, Skin Markers, Piercing Packs)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/10\/20250731003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250731003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250306 250416 250516  250616 250702 250708 250718 250728 250806 250808 250816 250818 250906 250916 250920 250925 250928 251002 251008 (Needles, Tapers, Sticks, Clamps, Tweezers, Rec. Tubes, Steel Rec. Tubes, Hemostats, Septum Clamp, Earth Series Piercing Tools, Skin Markers, Piercing Packs, Sample Packs)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/11\/20250903003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250903003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250308 250316 250326 250406 250608 250616  (Plastic Piercing Tools, Needles, Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/07\/20250326001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250326001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250406 250408 250514 250606 250608 250618 250708 250728 250816 250906 (Needles\/Tapers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/09\/20250731002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250731002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250516  (Markers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/07\/20250609001-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250609001-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250606  (Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/06\/20250519001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250519001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250608  (Piercing Tools, Tapers, Biodegradable Tools)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/06\/20250317001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250317001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250616 250708 250816 251002 251118 251130 251208) (Needles, Tapers. Septum Clamps, Earth Series Tools, White Markers, Purple Markers)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/12\/20251020001-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20251020001-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250706 250708 250808  (Clamps, Rec. Tubes, Piercing Packs, Markers, Sticks)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/09\/20250609003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250609003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250708 250718   (Jewelry, Hemo Clamp)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/08\/20250715001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250715001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250708 250728 250816 250906 250920 (Tapers, Hemo w Silicon Tip)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/10\/20250903001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250903001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250708 251218 260108 260228 (Needles, Tapers, Sticks, Rec. Tubes, Bead Changers, Piercing Packs w Drapes,Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/03\/20260210002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20260210002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250728 250806 251002 260108 260228 260308 260318 (Needles, Tapers, Rec. Tubes, Plastic Piercing Tools, Sample Packs)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/04\/20260210003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20260210003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250816  (Earth Series Sample Boxes, Plastic Tools)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/09\/20250731001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250731001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250920 251002 251008 251016 (Rec. Tubes, Steel Rec. Tubes, Earth Series Piercing Tools, Skin Markers, Piercing Packs)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/11\/20250903004-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250903004-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 250926 (Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2025\/10\/20250829002-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20250829002-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 251002 251118 250616 260108 260228 260308 (Needles, Tapers, Plastic Piercing Tools)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/03\/20260224001-Eo-Gas-Certification.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20260224001-Eo-Gas-Certification.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 251002 251118 251130 251208 251218 260108 (Needles, Tapers, Sticks, Rec Tubes, Clamps, Piercing Packs,  Packs w Drapes, &#038; Markers, )<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/02\/20251208003-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20251208003-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 251002 260118 260228 260308 260318 260326 260328 (Needles, Tapers, Sticks, Clamps, Markers, Steel Rec Tubes,Rec. Tubes, Plastic Piercing Tools, Piercing Packs &#038; Packs w Drapes, Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/04\/20260210004-Certificate-of-E.O.Gas-sterilization-1.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20260210004-Certificate-of-E.O.Gas-sterilization-1.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 251118 (Piercing Titanium Posts)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/01\/20251114001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20251114001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 251118 (Titanium Posts &#038; Titanium CZ Prong Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/01\/20251218001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20251218001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 251118 260108 (Needles, Tapers, Piercing Jewelry)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/03\/20260210001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20260210001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr><tr><td>Certificate of E.O. Gas Sterilization Lot #: 260228 260308 260318 260328 260408 (Needles, Tapers, Clamps, Markers, Rec. Tubes, Plastic Piercing Tools, Piercing Packs &#038; Packs w Drapes)<\/td><td><a href=\"https:\/\/stilettosupply.com\/wp-content\/uploads\/2026\/05\/20260225001-Certificate-of-E.O.Gas-sterilization.pdf\" class=\"dll-download-button document-library-button button btn\"  download=\"20260225001-Certificate-of-E.O.Gas-sterilization.pdf\" type=\"application\/pdf\">Descargar<\/a><\/td><\/tr>\t\t\t<\/tbody>\n\t\t<\/table>\n\t\t\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"TitleLink Certificate of E.O. Gas Sterilization Lot #: 100S (Jewelry)DownloadCertificate of E.O. Gas Sterilization Lot #: 240716 240916 (Rec. Tubes)DownloadCertificate","protected":false},"author":1,"featured_media":0,"parent":83,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-170","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sterilization Certification Search - Stiletto Supply<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stilettosupply.com\/es\/resources\/certification-search\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sterilization Certification Search - Stiletto Supply\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stilettosupply.com\/es\/resources\/certification-search\/\" \/>\n<meta property=\"og:site_name\" content=\"Stiletto Supply\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T16:24:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stilettosupply.com\\\/resources\\\/certification-search\\\/\",\"url\":\"https:\\\/\\\/stilettosupply.com\\\/resources\\\/certification-search\\\/\",\"name\":\"Sterilization Certification Search - Stiletto Supply\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stilettosupply.com\\\/#website\"},\"datePublished\":\"2022-05-18T19:58:37+00:00\",\"dateModified\":\"2024-03-11T16:24:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stilettosupply.com\\\/resources\\\/certification-search\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stilettosupply.com\\\/resources\\\/certification-search\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stilettosupply.com\\\/resources\\\/certification-search\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stilettosupply.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/stilettosupply.com\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sterilization Certification Search\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stilettosupply.com\\\/#website\",\"url\":\"https:\\\/\\\/stilettosupply.com\\\/\",\"name\":\"Stiletto Supply\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stilettosupply.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sterilization Certification Search - Stiletto Supply","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stilettosupply.com\/es\/resources\/certification-search\/","og_locale":"es_MX","og_type":"article","og_title":"Sterilization Certification Search - Stiletto Supply","og_url":"https:\/\/stilettosupply.com\/es\/resources\/certification-search\/","og_site_name":"Stiletto Supply","article_modified_time":"2024-03-11T16:24:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stilettosupply.com\/resources\/certification-search\/","url":"https:\/\/stilettosupply.com\/resources\/certification-search\/","name":"Sterilization Certification Search - Stiletto Supply","isPartOf":{"@id":"https:\/\/stilettosupply.com\/#website"},"datePublished":"2022-05-18T19:58:37+00:00","dateModified":"2024-03-11T16:24:21+00:00","breadcrumb":{"@id":"https:\/\/stilettosupply.com\/resources\/certification-search\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stilettosupply.com\/resources\/certification-search\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stilettosupply.com\/resources\/certification-search\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stilettosupply.com\/"},{"@type":"ListItem","position":2,"name":"Resources","item":"https:\/\/stilettosupply.com\/resources\/"},{"@type":"ListItem","position":3,"name":"Sterilization Certification Search"}]},{"@type":"WebSite","@id":"https:\/\/stilettosupply.com\/#website","url":"https:\/\/stilettosupply.com\/","name":"Suministro de estilete","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stilettosupply.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/pages\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/comments?post=170"}],"version-history":[{"count":2,"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/pages\/170\/revisions"}],"predecessor-version":[{"id":2230,"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/pages\/170\/revisions\/2230"}],"up":[{"embeddable":true,"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/pages\/83"}],"wp:attachment":[{"href":"https:\/\/stilettosupply.com\/es\/wp-json\/wp\/v2\/media?parent=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}